{"id":4294,"date":"2011-09-29T17:20:00","date_gmt":"2011-09-29T22:20:00","guid":{"rendered":"http:\/\/www.vidadigital.net\/blog\/2011\/10\/20\/creacin-de-categoras-y-sub-categoras-en-wordpress-com\/"},"modified":"2011-10-22T22:02:37","modified_gmt":"2011-10-23T03:02:37","slug":"creacin-de-categoras-y-sub-categoras-en-wordpress-com","status":"publish","type":"post","link":"http:\/\/www.vidadigital.net\/blog\/2011\/09\/29\/creacin-de-categoras-y-sub-categoras-en-wordpress-com\/","title":{"rendered":"Creaci&oacute;n de categor&iacute;as y sub-categor&iacute;as en WordPress.com"},"content":{"rendered":"<p>Al comenzar un blog en WP tienes dos categor\u00edas por defecto: Blogroll (para los enlaces) y Uncategorized (para las entradas). Son las categor\u00edas que se utilizar\u00e1n cuando te olvidas de clasificar las entradas y los enlaces. Por eso es que cuando se hace una b\u00fasqueda en Technorati vamos a ver que la categor\u00eda \u201cuncategorized\u201d es la m\u00e1s com\u00fan. Pero como podr\u00e1s entender esto no es lo m\u00e1s adecuado. As\u00ed que comenzaremos editando el t\u00edtulo de esa categor\u00eda:<\/p>\n<p>1. Ve a Entradas\u2014Categor\u00edas:<\/p>\n<p><a href=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image002.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; border-right-width: 0px; margin: 0px; padding-left: 0px; padding-right: 0px; display: inline; border-top-width: 0px; border-bottom-width: 0px; border-left-width: 0px; padding-top: 0px\" title=\"clip_image002\" border=\"0\" alt=\"clip_image002\" src=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image002_thumb.jpg\" width=\"141\" height=\"149\" \/><\/a><\/p>\n<p><a href=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image004.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; border-right-width: 0px; margin: 0px; padding-left: 0px; padding-right: 0px; display: inline; border-top-width: 0px; border-bottom-width: 0px; border-left-width: 0px; padding-top: 0px\" title=\"clip_image004\" border=\"0\" alt=\"clip_image004\" src=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image004_thumb.jpg\" width=\"468\" height=\"228\" \/><\/a><\/p>\n<p>En el lado izquierdo puedes a\u00f1adir nuevas categor\u00edas y en el derecho puedes administrar las mismas. Para editar una categor\u00eda, pon el cursor encima del nombre y aparecer\u00e1 el siguiente men\u00fa:<\/p>\n<p><a href=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image006.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; border-right-width: 0px; margin: 0px; padding-left: 0px; padding-right: 0px; display: inline; border-top-width: 0px; border-bottom-width: 0px; border-left-width: 0px; padding-top: 0px\" title=\"clip_image006\" border=\"0\" alt=\"clip_image006\" src=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image006_thumb.jpg\" width=\"210\" height=\"39\" \/><\/a><\/p>\n<p>Si seleccionas \u201cEdici\u00f3n R\u00e1pida\u201d puedes cambiar el nombre de la categor\u00eda, si escoges \u201cEditar\u201d puedes cambiar otras variables. Selecciona \u201cEditar\u201dy cambia el nombre de esa categor\u00eda. Sugiero que utilices el nombre de una categor\u00eda que sea central para tu blog.<\/p>\n<p><a href=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image008.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; border-right-width: 0px; padding-left: 0px; padding-right: 0px; display: inline; border-top-width: 0px; border-bottom-width: 0px; border-left-width: 0px; padding-top: 0px\" title=\"clip_image008\" border=\"0\" alt=\"clip_image008\" src=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image008_thumb.jpg\" width=\"476\" height=\"246\" \/><\/a><\/p>\n<p>Tienes ahora un espacio para editar el nombre, seleccionar si la quieres como una sub-categor\u00eda y&#160; a\u00f1adir una descripci\u00f3n de la misma. Finalmente,&#160; pulsas sobre \u201cActualizar\u201d.<\/p>\n<p>Para a\u00f1adir una nueva categor\u00eda vas a Entrada&#8212;-Categor\u00edas:<\/p>\n<p><a href=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image010.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; border-right-width: 0px; padding-left: 0px; padding-right: 0px; display: inline; border-top-width: 0px; border-bottom-width: 0px; border-left-width: 0px; padding-top: 0px\" title=\"clip_image010\" border=\"0\" alt=\"clip_image010\" src=\"http:\/\/academic.uprm.edu\/marion\/blogs-wlw\/7180fe99efdc_6F9A\/clip_image010_thumb.jpg\" width=\"215\" height=\"228\" \/><\/a><\/p>\n<p>Puedes ahora a\u00f1adir un nombre, escoger si es una categor\u00eda superior una sub-categor\u00eda y a\u00f1adir una descripci\u00f3n (opcional). Pulsa sobre \u201ca\u00f1adir nueva categor\u00eda\u201d para terminar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al comenzar un blog en WP tienes dos categor\u00edas por defecto: Blogroll (para los enlaces) y Uncategorized (para las entradas). Son las categor\u00edas que se utilizar\u00e1n cuando te olvidas de clasificar las entradas y los enlaces. Por eso es que cuando se hace una b\u00fasqueda en Technorati vamos a ver que la categor\u00eda \u201cuncategorized\u201d es &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"http:\/\/www.vidadigital.net\/blog\/2011\/09\/29\/creacin-de-categoras-y-sub-categoras-en-wordpress-com\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[61],"tags":[295],"series":[],"class_list":["post-4294","post","type-post","status-publish","format-standard","hentry","category-wordpress","tag-wordpresscom","item-wrap"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4tuv-17g","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/posts\/4294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/comments?post=4294"}],"version-history":[{"count":0,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/posts\/4294\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/media?parent=4294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/categories?post=4294"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/tags?post=4294"},{"taxonomy":"series","embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/series?post=4294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- WP Super Cache is installed but broken. The path to wp-cache-phase1.php in wp-content/advanced-cache.php must be fixed! -->