{"id":4376,"date":"2010-12-30T20:38:00","date_gmt":"2010-12-31T01:38:00","guid":{"rendered":"http:\/\/www.vidadigital.net\/blog\/2010\/12\/30\/trunk-ly-un-marcador-social-con-el-potencial-de-ser-una-buena-alternativa-a-delicious\/"},"modified":"2010-12-30T20:38:00","modified_gmt":"2010-12-31T01:38:00","slug":"trunk-ly-un-marcador-social-con-el-potencial-de-ser-una-buena-alternativa-a-delicious","status":"publish","type":"post","link":"http:\/\/www.vidadigital.net\/blog\/2010\/12\/30\/trunk-ly-un-marcador-social-con-el-potencial-de-ser-una-buena-alternativa-a-delicious\/","title":{"rendered":"Trunk.ly: un marcador social con el potencial de ser una buena alternativa a Delicious"},"content":{"rendered":"<p><a href=\"http:\/\/trunk.ly\/\">Trunk.ly<\/a> es un nuevo sistema de social&#160; bookmarking&#160; con&#160; potencial de convertirse en una buena alternativa para los usuarios de <a href=\"http:\/\/www.delicious.com\">Delicious<\/a>.&#160; Tiene muy buena pinta: similar a la interfaz de Delicious; archiva autom\u00e1ticamente enlaces de <a href=\"http:\/\/twitter.com\">Twitter<\/a>,&#160; <a href=\"http:\/\/facebook.com\">Facebook<\/a> y Delicious;&#160; y posee una velocidad impresionante. Adem\u00e1s, qued\u00e9 muy impresionado por su sistema de b\u00fasqueda: es de lo mejor que he visto. <\/p>\n<p>El proceso de importar mis 20,000 enlaces de Delicious se llev\u00f3 a cabo en poco tiempo. Puede acceder mis enlaces pulsando en la imagen:<\/p>\n<p><a href=\"http:\/\/trunk.ly\/digizen\/\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; border-right-width: 0px; padding-left: 0px; padding-right: 0px; display: inline; border-top-width: 0px; border-bottom-width: 0px; border-left-width: 0px; padding-top: 0px\" title=\"captured_Image.png\" border=\"0\" alt=\"captured_Image.png\" src=\"http:\/\/academic.uprm.edu\/~marion\/blogs-wlw\/a17b4bfba5e6_BE27\/captured_Image.png.png\" width=\"574\" height=\"213\" \/><\/a> <\/p>\n<p>Y lo mejor es que Trunk.ly es un sistema en constante desarrollo, contrario a Delicious que est\u00e1 muerto en vida. Merece la atenci\u00f3n de todos los que pensamos que un sistema de social bookmarking es esencial para compartir y manejar los recursos que valoramos en Internet. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trunk.ly es un nuevo sistema de social&#160; bookmarking&#160; con&#160; potencial de convertirse en una buena alternativa para los usuarios de Delicious.&#160; Tiene muy buena pinta: similar a la interfaz de Delicious; archiva autom\u00e1ticamente enlaces de Twitter,&#160; Facebook y Delicious;&#160; y posee una velocidad impresionante. Adem\u00e1s, qued\u00e9 muy impresionado por su sistema de b\u00fasqueda: es de &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"http:\/\/www.vidadigital.net\/blog\/2010\/12\/30\/trunk-ly-un-marcador-social-con-el-potencial-de-ser-una-buena-alternativa-a-delicious\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[65],"tags":[688],"series":[],"class_list":["post-4376","post","type-post","status-publish","format-standard","hentry","category-social-bookmarking","tag-trunkly","item-wrap"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4tuv-18A","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/posts\/4376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/comments?post=4376"}],"version-history":[{"count":0,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/posts\/4376\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/media?parent=4376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/categories?post=4376"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/tags?post=4376"},{"taxonomy":"series","embeddable":true,"href":"http:\/\/www.vidadigital.net\/blog\/wp-json\/wp\/v2\/series?post=4376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- WP Super Cache is installed but broken. The path to wp-cache-phase1.php in wp-content/advanced-cache.php must be fixed! -->